{"id":280066,"date":"2026-09-02T03:43:46","date_gmt":"2026-09-02T03:43:46","guid":{"rendered":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/"},"modified":"2026-09-02T03:43:48","modified_gmt":"2026-09-02T03:43:48","slug":"a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia","status":"publish","type":"job_listing","link":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/","title":{"rendered":"Imaging &#038; Radiology &#8211; Echo Technologist (Travel)"},"content":{"rendered":"\n<div style=\"display: none !important;\"><strong>Job Description &#8211;<\/strong>\r\n<i>Medasource provides equal employment opportunities (EEO) to all employees and applicants for employment without regard to race, color, religion, national origin, age, sex, citizenship, disability, genetic information, gender, sexual orientation, gender identity, marital status, amnesty or status as a covered veteran in accordance with applicable federal, state, and local laws.<\/i>\r\n<p dir=\"auto\" align=\"left\"><span style=\"text-decoration: underline;\"><strong>Benefits &amp; Perks:<\/strong><\/span><\/p>\r\n<p dir=\"auto\" align=\"left\"><em><strong>Medasource Healthcare<\/strong> offers competitive medical, dental, vision, Health Savings Account, Dependent Care FSA, and supplemental coverage with plans that can fit each employee\u2019s needs. We offer a 401k plan that includes a company match and is fully vested after you become eligible, paid time off, sick time, and paid company holidays. We also offer an Employee Assistance Program (EAP) that provides services like virtual counseling, financial services, legal services, life coaching, etc.<\/em><\/p>\r\n<p dir=\"auto\" align=\"left\"><span style=\"text-decoration: underline;\"><strong>Pay Disclaimer:<\/strong><\/span><strong>\u00a0<\/strong><\/p>\r\n<p dir=\"auto\" align=\"left\"><em>The pay range for this job level is a general guideline only and not a guarantee of compensation or salary. Additional factors considered in extending an offer include (but are not limited to) responsibilities of the job, education, experience, knowledge, skills, and abilities, as well as internal equity, alignment with market data, applicable bargaining agreement (if any), or other law.<\/em><\/p>\r\n<p class=\"custom-white\">a1Wcv000000z7arEAA<\/p>\r\n\r\n<\/div>\r\n&nbsp;\n","protected":false},"author":0,"featured_media":82,"template":"","meta":{"inline_featured_image":false,"_promoted":"","_job_location":"Salem Virginia","_application":"applications@staffingfuture.com","_company_name":"Medasource","_company_website":"","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job-types":[8],"class_list":["post-280066","job_listing","type-job_listing","status-publish","has-post-thumbnail","hentry","job-type-contract"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Imaging &amp; Radiology - Echo Technologist, Salem Virginia<\/title>\n<meta name=\"description\" content=\"Imaging &amp; Radiology - Echo Technologist, Salem Virginia - Search for the latest jobs from Medasource. We have this role currently available - Imaging &amp; Radiology - Echo Technologist Salem Virginia - Apply online quickly and easily.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imaging &amp; Radiology - Echo Technologist, Salem Virginia\" \/>\n<meta property=\"og:description\" content=\"Imaging &amp; Radiology - Echo Technologist, Salem Virginia - Search for the latest jobs from Medasource. We have this role currently available - Imaging &amp; Radiology - Echo Technologist Salem Virginia - Apply online quickly and easily.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/\" \/>\n<meta property=\"og:site_name\" content=\"Medasource Healthcare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T03:43:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/wp-content\/uploads\/2024\/11\/cropped-medasource-ico.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Imaging &amp; Radiology - Echo Technologist, Salem Virginia\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/job\\\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\\\/\",\"url\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/job\\\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\\\/\",\"name\":\"Imaging & Radiology - Echo Technologist, Salem Virginia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/job\\\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/job\\\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-medasource-ico.png\",\"datePublished\":\"2026-09-02T03:43:46+00:00\",\"dateModified\":\"2026-09-02T03:43:48+00:00\",\"description\":\"Imaging & Radiology - Echo Technologist, Salem Virginia - Search for the latest jobs from Medasource. We have this role currently available - Imaging & Radiology - Echo Technologist Salem Virginia - Apply online quickly and easily.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/job\\\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/job\\\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/job\\\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-medasource-ico.png\",\"contentUrl\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-medasource-ico.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/job\\\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imaging &#038; Radiology &#8211; Echo Technologist (Travel)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/#website\",\"url\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/\",\"name\":\"Medasource Healthcare\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/#organization\",\"name\":\"Medasource Healthcare\",\"url\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-medasource-ico-1.png\",\"contentUrl\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-medasource-ico-1.png\",\"width\":512,\"height\":512,\"caption\":\"Medasource Healthcare\"},\"image\":{\"@id\":\"https:\\\/\\\/healthcarejobs.medasource.com\\\/healthcarejobs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imaging & Radiology - Echo Technologist, Salem Virginia","description":"Imaging & Radiology - Echo Technologist, Salem Virginia - Search for the latest jobs from Medasource. We have this role currently available - Imaging & Radiology - Echo Technologist Salem Virginia - Apply online quickly and easily.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/","og_locale":"en_US","og_type":"article","og_title":"Imaging & Radiology - Echo Technologist, Salem Virginia","og_description":"Imaging & Radiology - Echo Technologist, Salem Virginia - Search for the latest jobs from Medasource. We have this role currently available - Imaging & Radiology - Echo Technologist Salem Virginia - Apply online quickly and easily.","og_url":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/","og_site_name":"Medasource Healthcare","article_modified_time":"2026-09-02T03:43:48+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/wp-content\/uploads\/2024\/11\/cropped-medasource-ico.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"Imaging & Radiology - Echo Technologist, Salem Virginia","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/","url":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/","name":"Imaging & Radiology - Echo Technologist, Salem Virginia","isPartOf":{"@id":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/#primaryimage"},"image":{"@id":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/#primaryimage"},"thumbnailUrl":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/wp-content\/uploads\/2024\/11\/cropped-medasource-ico.png","datePublished":"2026-09-02T03:43:46+00:00","dateModified":"2026-09-02T03:43:48+00:00","description":"Imaging & Radiology - Echo Technologist, Salem Virginia - Search for the latest jobs from Medasource. We have this role currently available - Imaging & Radiology - Echo Technologist Salem Virginia - Apply online quickly and easily.","breadcrumb":{"@id":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/#primaryimage","url":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/wp-content\/uploads\/2024\/11\/cropped-medasource-ico.png","contentUrl":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/wp-content\/uploads\/2024\/11\/cropped-medasource-ico.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/job\/a1wcv000000z7areaa-imaging-radiology-echo-technologist-salem-virginia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/"},{"@type":"ListItem","position":2,"name":"Imaging &#038; Radiology &#8211; Echo Technologist (Travel)"}]},{"@type":"WebSite","@id":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/#website","url":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/","name":"Medasource Healthcare","description":"","publisher":{"@id":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/#organization","name":"Medasource Healthcare","url":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/#\/schema\/logo\/image\/","url":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/wp-content\/uploads\/2024\/11\/cropped-cropped-medasource-ico-1.png","contentUrl":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/wp-content\/uploads\/2024\/11\/cropped-cropped-medasource-ico-1.png","width":512,"height":512,"caption":"Medasource Healthcare"},"image":{"@id":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/wp-json\/wp\/v2\/job-listings\/280066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/wp-json\/wp\/v2\/types\/job_listing"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/wp-json\/wp\/v2\/media\/82"}],"wp:attachment":[{"href":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/wp-json\/wp\/v2\/media?parent=280066"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/healthcarejobs.medasource.com\/healthcarejobs\/wp-json\/wp\/v2\/job-types?post=280066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}